{"id":2663,"date":"2019-09-26T16:30:55","date_gmt":"2021-11-22T11:36:12","guid":{"rendered":"https:\/\/zum-pleitegeier.de\/product\/baked-farmers-bread-2\/"},"modified":"2021-11-25T15:35:27","modified_gmt":"2021-11-25T14:35:27","slug":"baked-farmers-bread","status":"publish","type":"product","link":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/","title":{"rendered":"16. Baked farmer&#8217;s bread"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Baked brown bread, with bacon, onions &amp; cheese<\/p>\n","protected":false},"featured_media":2498,"template":"","meta":[],"product_brand":[],"product_cat":[119],"product_tag":[],"class_list":{"0":"post-2663","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-small-fine","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>16. Baked farmer&#039;s bread - Zum Pleitegeier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"16. Baked farmer&#039;s bread - Zum Pleitegeier\" \/>\n<meta property=\"og:description\" content=\"Baked brown bread, with bacon, onions &amp; cheese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/\" \/>\n<meta property=\"og:site_name\" content=\"Zum Pleitegeier\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pleitegeier.erlangen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-25T14:35:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/\",\"url\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/\",\"name\":\"16. Baked farmer's bread - Zum Pleitegeier\",\"isPartOf\":{\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png\",\"datePublished\":\"2021-11-22T11:36:12+00:00\",\"dateModified\":\"2021-11-25T14:35:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#primaryimage\",\"url\":\"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png\",\"contentUrl\":\"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/zum-pleitegeier.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/zum-pleitegeier.de\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"16. Baked farmer&#8217;s bread\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/#website\",\"url\":\"https:\/\/zum-pleitegeier.de\/en\/\",\"name\":\"Zum Pleitegeier\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zum-pleitegeier.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/#organization\",\"name\":\"Zum Pleitegeier\",\"url\":\"https:\/\/zum-pleitegeier.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/04\/logo-pg.png\",\"contentUrl\":\"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/04\/logo-pg.png\",\"width\":243,\"height\":240,\"caption\":\"Zum Pleitegeier\"},\"image\":{\"@id\":\"https:\/\/zum-pleitegeier.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pleitegeier.erlangen\/\",\"https:\/\/www.instagram.com\/pleitegeier_erlangen\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"16. Baked farmer's bread - Zum Pleitegeier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/","og_locale":"en_US","og_type":"article","og_title":"16. Baked farmer's bread - Zum Pleitegeier","og_description":"Baked brown bread, with bacon, onions &amp; cheese","og_url":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/","og_site_name":"Zum Pleitegeier","article_publisher":"https:\/\/www.facebook.com\/pleitegeier.erlangen\/","article_modified_time":"2021-11-25T14:35:27+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/","url":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/","name":"16. Baked farmer's bread - Zum Pleitegeier","isPartOf":{"@id":"https:\/\/zum-pleitegeier.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#primaryimage"},"image":{"@id":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#primaryimage"},"thumbnailUrl":"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png","datePublished":"2021-11-22T11:36:12+00:00","dateModified":"2021-11-25T14:35:27+00:00","breadcrumb":{"@id":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#primaryimage","url":"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png","contentUrl":"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/09\/bauernbrot.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/zum-pleitegeier.de\/en\/product\/baked-farmers-bread\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zum-pleitegeier.de\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/zum-pleitegeier.de\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"16. Baked farmer&#8217;s bread"}]},{"@type":"WebSite","@id":"https:\/\/zum-pleitegeier.de\/en\/#website","url":"https:\/\/zum-pleitegeier.de\/en\/","name":"Zum Pleitegeier","description":"","publisher":{"@id":"https:\/\/zum-pleitegeier.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zum-pleitegeier.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zum-pleitegeier.de\/en\/#organization","name":"Zum Pleitegeier","url":"https:\/\/zum-pleitegeier.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zum-pleitegeier.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/04\/logo-pg.png","contentUrl":"https:\/\/zum-pleitegeier.de\/wp-content\/uploads\/2019\/04\/logo-pg.png","width":243,"height":240,"caption":"Zum Pleitegeier"},"image":{"@id":"https:\/\/zum-pleitegeier.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pleitegeier.erlangen\/","https:\/\/www.instagram.com\/pleitegeier_erlangen\/"]}]}},"_links":{"self":[{"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/product\/2663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/media\/2498"}],"wp:attachment":[{"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/media?parent=2663"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/product_brand?post=2663"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/product_cat?post=2663"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zum-pleitegeier.de\/en\/wp-json\/wp\/v2\/product_tag?post=2663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}